{"id":10,"date":"2026-06-23T20:41:13","date_gmt":"2026-06-23T20:41:13","guid":{"rendered":"http:\/\/francerezy.cluster015.ovh.net\/?page_id=10"},"modified":"2026-08-29T21:57:56","modified_gmt":"2026-08-29T21:57:56","slug":"demander-une-expedition","status":"publish","type":"page","link":"https:\/\/antsound.net\/index.php\/demander-une-expedition\/","title":{"rendered":"Exp\u00e9dition unique"},"content":{"rendered":"\n<style data-wp-block-html=\"css\">\n<style>\n  \/* Conteneur g\u00e9n\u00e9ral *\/\n  .ml-form {\n    max-width: 650px;\n    margin: 0 auto;\n    padding: 10px 5px;\n  }\n\n  \/* Titres *\/\n  .ml-form h2, .ml-form h3 {\n    margin-top: 20px;\n    margin-bottom: 8px;\n    font-size: 20px;\n  }\n\n  \/* Champs *\/\n  .ml-input,\n  .ml-form input,\n  .ml-form select {\n    width: 100%;\n    padding: 9px 12px;\n    font-size: 15px;\n    border: 1px solid #ccc;\n    border-radius: 6px;\n    margin-bottom: 10px;\n    box-sizing: border-box;\n  }\n\n  \/* Lignes flexibles *\/\n  .ml-row {\n    display: flex;\n    gap: 10px;\n    margin-bottom: 10px;\n  }\n\n  .ml-row .ml-input,\n  .ml-row input {\n    flex: 1;\n  }\n\n  \/* Bouton *\/\n  #submitBoxtal {\n    padding: 12px 16px;\n    font-size: 16px;\n    background: #007bff;\n    color: white;\n    border: none;\n    border-radius: 6px;\n    cursor: pointer;\n    width: 100%;\n    margin-top: 15px;\n  }\n\n  #submitBoxtal:hover {\n    background: #005fcc;\n  }\n\n  \/* Zone des offres *\/\n  #boxtal_offers {\n    margin-top: 20px;\n    font-size: 15px;\n  }\n<\/style>\n\n\n\n<div class=\"forminator-guttenberg\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-595 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-595\" data-uid=\"6a97a213432e7\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-595\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-595 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"595\"\n\t\t\t\tenctype=\"multipart\/form-data\" data-color-option=\"theme\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a97a213432e7\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div role=\"tablist\" class=\"forminator-pagination-steps\" aria-label=\"Pagination\"><\/div><div\n\t\t\t\ttabindex=\"-1\"\n\t\t\t\trole=\"tabpanel\"\n\t\t\t\tid=\"forminator-custom-form-595--page-0\"\n\t\t\t\tclass=\"forminator-pagination forminator-pagination-start\"\n\t\t\t\taria-labelledby=\"forminator-custom-form-595--page-0-label\"\n\t\t\t\tdata-step=\"0\"\n\t\t\t\tdata-label=\"Termin\u00e9\"\n\t\t\t\tdata-actual-label=\"Page 1\"\n\t\t\t\tdata-name=\"page-break-1\"\n\t\t\t><div class=\"forminator-pagination--content\"><div class=\"forminator-row\"><div id=\"group-1\" class=\"forminator-field-group forminator-col forminator-col-12  Blank Form\"><label class=\"forminator-label forminator-repeater-label\">Groupe de champs<\/label><div class=\"forminator-all-group-copies forminator-repeater-field\"><div class=\"forminator-grouped-fields\" data-options=\"{&quot;is_repeater&quot;:true,&quot;min_type&quot;:&quot;custom&quot;,&quot;max_type&quot;:&quot;custom&quot;,&quot;min&quot;:1,&quot;max&quot;:5,&quot;add_text&quot;:&quot;Ajout d&#039;adresse&quot;,&quot;remove_text&quot;:&quot;Retirer l&#039;adresse&quot;,&quot;action_element_type&quot;:&quot;button&quot;}\"><div class=\"forminator-row\"><div id=\"name-2\" class=\"forminator-field-name forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-name-2_6a97a213432e7\" id=\"forminator-field-name-2_6a97a213432e7-label\" class=\"forminator-label\">Nom et pr\u00e9nom <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-2\" value=\"\" placeholder=\"\" id=\"forminator-field-name-2_6a97a213432e7\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-2\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-email-2_6a97a213432e7\" id=\"forminator-field-email-2_6a97a213432e7-label\" class=\"forminator-label\">Adresse de messagerie <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-2\" value=\"\" placeholder=\"\" id=\"forminator-field-email-2_6a97a213432e7\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-2\" class=\"forminator-field-address forminator-col forminator-col-12  ban-autocomplete\"><div class=\"forminator-row\"><div id=\"address-2-street_address\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-address-2-street_address_6a97a213432e7\" id=\"forminator-field-address-2-street_address_6a97a213432e7-label\" class=\"forminator-label\">Rue <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"address-2-street_address\" placeholder=\"\" id=\"forminator-field-address-2-street_address_6a97a213432e7\" class=\"forminator-input\" data-required=\"1\" aria-required=\"true\" autocomplete=\"address-line1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-2-address_line\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-address-2-address_line_6a97a213432e7\" id=\"forminator-field-address-2-address_line_6a97a213432e7-label\" class=\"forminator-label\">Appartement, suite, etc.<\/label><input type=\"text\" name=\"address-2-address_line\" placeholder=\"\" id=\"forminator-field-address-2-address_line_6a97a213432e7\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-line2\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-2-city\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-2-city_6a97a213432e7\" id=\"forminator-field-address-2-city_6a97a213432e7-label\" class=\"forminator-label\">Ville<\/label><input type=\"text\" name=\"address-2-city\" placeholder=\"\" id=\"forminator-field-address-2-city_6a97a213432e7\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-level2\" value=\"\" \/><\/div><\/div><div id=\"address-2-state\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-2-state_6a97a213432e7\" id=\"forminator-field-address-2-state_6a97a213432e7-label\" class=\"forminator-label\">\u00c9tat\/Province<\/label><input type=\"text\" name=\"address-2-state\" placeholder=\"\" id=\"forminator-field-address-2-state_6a97a213432e7\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-level1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-2-zip\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-2-zip_6a97a213432e7\" id=\"forminator-field-address-2-zip_6a97a213432e7-label\" class=\"forminator-label\">Code postal<\/label><input type=\"text\" name=\"address-2-zip\" placeholder=\"\" id=\"forminator-field-address-2-zip_6a97a213432e7\" class=\"forminator-input\" autocomplete=\"postal-code\" value=\"\" \/><\/div><\/div><div id=\"address-2-country\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-595__field--address-2-country_6a97a213432e7\" id=\"forminator-field-595__field--address-2-country_6a97a213432e7-label\" class=\"forminator-label\">Pays<\/label><select name=\"address-2-country\" id=\"forminator-field-595__field--address-2-country_6a97a213432e7\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"S\u00e9lectionner un pays\" autocomplete=\"country-name\" data-default-value=\"\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Afrique du Sud\" data-country-code=\"ZA\" >Afrique du Sud<\/option><option value=\"Albanie\" data-country-code=\"AL\" >Albanie<\/option><option value=\"Alg\u00e9rie\" data-country-code=\"DZ\" >Alg\u00e9rie<\/option><option value=\"Allemagne\" data-country-code=\"DE\" >Allemagne<\/option><option value=\"Andorre\" data-country-code=\"AD\" >Andorre<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctique\" data-country-code=\"AQ\" >Antarctique<\/option><option value=\"Antigua &amp; Barbuda\" data-country-code=\"AG\" >Antigua &amp; Barbuda<\/option><option value=\"Arabie saoudite\" data-country-code=\"SA\" >Arabie saoudite<\/option><option value=\"Argentine\" data-country-code=\"AR\" >Argentine<\/option><option value=\"Arm\u00e9nie\" data-country-code=\"AM\" >Arm\u00e9nie<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Ascension Island\" data-country-code=\"AC\" >Ascension Island<\/option><option value=\"Australie\" data-country-code=\"AU\" >Australie<\/option><option value=\"Autriche\" data-country-code=\"AT\" >Autriche<\/option><option value=\"Azerba\u00efdjan\" data-country-code=\"AZ\" >Azerba\u00efdjan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahre\u00efn\" data-country-code=\"BH\" >Bahre\u00efn<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Barbade\" data-country-code=\"BB\" >Barbade<\/option><option value=\"Belgique\" data-country-code=\"BE\" >Belgique<\/option><option value=\"Bermudes\" data-country-code=\"BM\" >Bermudes<\/option><option value=\"Bhoutan\" data-country-code=\"BT\" >Bhoutan<\/option><option value=\"Bi\u00e9lorussie\" data-country-code=\"BY\" >Bi\u00e9lorussie<\/option><option value=\"Bolivie\" data-country-code=\"BO\" >Bolivie<\/option><option value=\"Bosnie-Herz\u00e9govine\" data-country-code=\"BA\" >Bosnie-Herz\u00e9govine<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"British Virgin Islands\" data-country-code=\"VG\" >British Virgin Islands<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Br\u00e9sil\" data-country-code=\"BR\" >Br\u00e9sil<\/option><option value=\"Bulgarie\" data-country-code=\"BG\" >Bulgarie<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"B\u00e9lize\" data-country-code=\"BZ\" >B\u00e9lize<\/option><option value=\"B\u00e9nin\" data-country-code=\"BJ\" >B\u00e9nin<\/option><option value=\"Cambodge\" data-country-code=\"KH\" >Cambodge<\/option><option value=\"Cameroun\" data-country-code=\"CM\" >Cameroun<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Cap Vert\" data-country-code=\"CV\" >Cap Vert<\/option><option value=\"Caribbean Netherlands\" data-country-code=\"BQ\" >Caribbean Netherlands<\/option><option value=\"Chili\" data-country-code=\"CL\" >Chili<\/option><option value=\"China\" data-country-code=\"CN\" >China<\/option><option value=\"Chypre\" data-country-code=\"CY\" >Chypre<\/option><option value=\"Cit\u00e9 du Vatican\" data-country-code=\"VA\" >Cit\u00e9 du Vatican<\/option><option value=\"Colombie\" data-country-code=\"CO\" >Colombie<\/option><option value=\"Comores\" data-country-code=\"KM\" >Comores<\/option><option value=\"Congo, R\u00e9publique du\" data-country-code=\"CG\" >Congo, R\u00e9publique du<\/option><option value=\"Congo, R\u00e9publique d\u00e9mocratique du\" data-country-code=\"CD\" >Congo, R\u00e9publique d\u00e9mocratique du<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"Croatie\" data-country-code=\"HR\" >Croatie<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Czechia\" data-country-code=\"CZ\" >Czechia<\/option><option value=\"C\u00f4te d\u2019Ivoire\" data-country-code=\"CI\" >C\u00f4te d\u2019Ivoire<\/option><option value=\"Danemark\" data-country-code=\"DK\" >Danemark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominique\" data-country-code=\"DM\" >Dominique<\/option><option value=\"Espagne\" data-country-code=\"ES\" >Espagne<\/option><option value=\"Estonie\" data-country-code=\"EE\" >Estonie<\/option><option value=\"Eswatini\" data-country-code=\"SZ\" >Eswatini<\/option><option value=\"Fidji\" data-country-code=\"FJ\" >Fidji<\/option><option value=\"Finlande\" data-country-code=\"FI\" >Finlande<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambie\" data-country-code=\"GM\" >Gambie<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Grenade\" data-country-code=\"GD\" >Grenade<\/option><option value=\"Groenland\" data-country-code=\"GL\" >Groenland<\/option><option value=\"Gr\u00e8ce\" data-country-code=\"GR\" >Gr\u00e8ce<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guat\u00e9mala\" data-country-code=\"GT\" >Guat\u00e9mala<\/option><option value=\"Guernesey\" data-country-code=\"GG\" >Guernesey<\/option><option value=\"Guin\u00e9e\" data-country-code=\"GN\" >Guin\u00e9e<\/option><option value=\"Guin\u00e9e \u00e9quatoriale\" data-country-code=\"GQ\" >Guin\u00e9e \u00e9quatoriale<\/option><option value=\"Guin\u00e9e-Bissau\" data-country-code=\"GW\" >Guin\u00e9e-Bissau<\/option><option value=\"Guyana\" data-country-code=\"GY\" >Guyana<\/option><option value=\"Guyane fran\u00e7aise\" data-country-code=\"GF\" >Guyane fran\u00e7aise<\/option><option value=\"G\u00e9orgie\" data-country-code=\"GE\" >G\u00e9orgie<\/option><option value=\"G\u00e9orgie du Sud et Sandwich du Sud\" data-country-code=\"GS\" >G\u00e9orgie du Sud et Sandwich du Sud<\/option><option value=\"Ha\u00efti\" data-country-code=\"HT\" >Ha\u00efti<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong SAR China\" data-country-code=\"HK\" >Hong Kong SAR China<\/option><option value=\"Hongrie\" data-country-code=\"HU\" >Hongrie<\/option><option value=\"Inde\" data-country-code=\"IN\" >Inde<\/option><option value=\"Indon\u00e9sie\" data-country-code=\"ID\" >Indon\u00e9sie<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Irlande\" data-country-code=\"IE\" >Irlande<\/option><option value=\"Islande\" data-country-code=\"IS\" >Islande<\/option><option value=\"Isle of Man\" data-country-code=\"IM\" >Isle of Man<\/option><option value=\"Isra\u00ebl\" data-country-code=\"IL\" >Isra\u00ebl<\/option><option value=\"Italie\" data-country-code=\"IT\" >Italie<\/option><option value=\"Jama\u00efque\" data-country-code=\"JM\" >Jama\u00efque<\/option><option value=\"Japon\" data-country-code=\"JP\" >Japon<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Jordanie\" data-country-code=\"JO\" >Jordanie<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kirghizistan\" data-country-code=\"KG\" >Kirghizistan<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kowe\u00eft\" data-country-code=\"KW\" >Kowe\u00eft<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Lettonie\" data-country-code=\"LV\" >Lettonie<\/option><option value=\"Liban\" data-country-code=\"LB\" >Liban<\/option><option value=\"Libye\" data-country-code=\"LY\" >Libye<\/option><option value=\"Lib\u00e9ria\" data-country-code=\"LR\" >Lib\u00e9ria<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lituanie\" data-country-code=\"LT\" >Lituanie<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macao SAR China\" data-country-code=\"MO\" >Macao SAR China<\/option><option value=\"Mac\u00e9doine du Nord\" data-country-code=\"MK\" >Mac\u00e9doine du Nord<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malaisie\" data-country-code=\"MY\" >Malaisie<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malte\" data-country-code=\"MT\" >Malte<\/option><option value=\"Maroc\" data-country-code=\"MA\" >Maroc<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritanie\" data-country-code=\"MR\" >Mauritanie<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexique\" data-country-code=\"MX\" >Mexique<\/option><option value=\"Micron\u00e9sie\" data-country-code=\"FM\" >Micron\u00e9sie<\/option><option value=\"Moldavie\" data-country-code=\"MD\" >Moldavie<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolie\" data-country-code=\"MN\" >Mongolie<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Mont\u00e9n\u00e9gro\" data-country-code=\"ME\" >Mont\u00e9n\u00e9gro<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibie\" data-country-code=\"NA\" >Namibie<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nig\u00e9ria\" data-country-code=\"NG\" >Nig\u00e9ria<\/option><option value=\"Niu\u00e9\" data-country-code=\"NU\" >Niu\u00e9<\/option><option value=\"North Korea\" data-country-code=\"KP\" >North Korea<\/option><option value=\"Norv\u00e8ge\" data-country-code=\"NO\" >Norv\u00e8ge<\/option><option value=\"Nouvelle-Cal\u00e9donie\" data-country-code=\"NC\" >Nouvelle-Cal\u00e9donie<\/option><option value=\"Nouvelle-Z\u00e9lande\" data-country-code=\"NZ\" >Nouvelle-Z\u00e9lande<\/option><option value=\"N\u00e9pal\" data-country-code=\"NP\" >N\u00e9pal<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Ouganda\" data-country-code=\"UG\" >Ouganda<\/option><option value=\"Ouzb\u00e9kistan\" data-country-code=\"UZ\" >Ouzb\u00e9kistan<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palaos\" data-country-code=\"PW\" >Palaos<\/option><option value=\"Palestinian Territories\" data-country-code=\"PS\" >Palestinian Territories<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papouasie-Nouvelle-Guin\u00e9e\" data-country-code=\"PG\" >Papouasie-Nouvelle-Guin\u00e9e<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Pays-Bas\" data-country-code=\"NL\" >Pays-Bas<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pologne\" data-country-code=\"PL\" >Pologne<\/option><option value=\"Polyn\u00e9sie fran\u00e7aise\" data-country-code=\"PF\" >Polyn\u00e9sie fran\u00e7aise<\/option><option value=\"Porto Rico\" data-country-code=\"PR\" >Porto Rico<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"P\u00e9rou\" data-country-code=\"PE\" >P\u00e9rou<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Roumanie\" data-country-code=\"RO\" >Roumanie<\/option><option value=\"Royaume-Uni\" data-country-code=\"GB\" >Royaume-Uni<\/option><option value=\"Russie\" data-country-code=\"RU\" >Russie<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"R\u00e9publique centrafricaine\" data-country-code=\"CF\" >R\u00e9publique centrafricaine<\/option><option value=\"R\u00e9publique dominicaine\" data-country-code=\"DO\" >R\u00e9publique dominicaine<\/option><option value=\"R\u00e9publique d\u00e9mocratique populaire du Laos\" data-country-code=\"LA\" >R\u00e9publique d\u00e9mocratique populaire du Laos<\/option><option value=\"R\u00e9union\" data-country-code=\"RE\" >R\u00e9union<\/option><option value=\"Sahara occidental\" data-country-code=\"EH\" >Sahara occidental<\/option><option value=\"Saint-Kitts-et-Nevis\" data-country-code=\"KN\" >Saint-Kitts-et-Nevis<\/option><option value=\"Saint-Marin\" data-country-code=\"SM\" >Saint-Marin<\/option><option value=\"Saint-Martin (royaume des Pays-Bas)\" data-country-code=\"SX\" >Saint-Martin (royaume des Pays-Bas)<\/option><option value=\"Saint-Vincent-et-les-Grenadines\" data-country-code=\"VC\" >Saint-Vincent-et-les-Grenadines<\/option><option value=\"Sainte-H\u00e9l\u00e8ne\" data-country-code=\"SH\" >Sainte-H\u00e9l\u00e8ne<\/option><option value=\"Sainte-Lucie\" data-country-code=\"LC\" >Sainte-Lucie<\/option><option value=\"Salvador\" data-country-code=\"SV\" >Salvador<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"Samoa am\u00e9ricaines\" data-country-code=\"AS\" >Samoa am\u00e9ricaines<\/option><option value=\"Serbie\" data-country-code=\"RS\" >Serbie<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapour\" data-country-code=\"SG\" >Singapour<\/option><option value=\"Slovaquie\" data-country-code=\"SK\" >Slovaquie<\/option><option value=\"Slov\u00e9nie\" data-country-code=\"SI\" >Slov\u00e9nie<\/option><option value=\"Somalie\" data-country-code=\"SO\" >Somalie<\/option><option value=\"Soudan\" data-country-code=\"SD\" >Soudan<\/option><option value=\"South Korea\" data-country-code=\"KR\" >South Korea<\/option><option value=\"South Sudan\" data-country-code=\"SS\" >South Sudan<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"St. Barth\u00e9lemy\" data-country-code=\"BL\" >St. Barth\u00e9lemy<\/option><option value=\"St. Martin\" data-country-code=\"MF\" >St. Martin<\/option><option value=\"St. Pierre &amp; Miquelon\" data-country-code=\"PM\" >St. Pierre &amp; Miquelon<\/option><option value=\"Suisse\" data-country-code=\"CH\" >Suisse<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Su\u00e8de\" data-country-code=\"SE\" >Su\u00e8de<\/option><option value=\"Svalbard et Jan Mayen\" data-country-code=\"SJ\" >Svalbard et Jan Mayen<\/option><option value=\"Syrie\" data-country-code=\"SY\" >Syrie<\/option><option value=\"S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe\" data-country-code=\"ST\" >S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe<\/option><option value=\"S\u00e9n\u00e9gal\" data-country-code=\"SN\" >S\u00e9n\u00e9gal<\/option><option value=\"Tadjikistan\" data-country-code=\"TJ\" >Tadjikistan<\/option><option value=\"Taiwan\" data-country-code=\"TW\" >Taiwan<\/option><option value=\"Tanzanie\" data-country-code=\"TZ\" >Tanzanie<\/option><option value=\"Tchad\" data-country-code=\"TD\" >Tchad<\/option><option value=\"Terres australes et antarctiques fran\u00e7aises\" data-country-code=\"TF\" >Terres australes et antarctiques fran\u00e7aises<\/option><option value=\"Territoire britannique de l\u2019oc\u00e9an Indien\" data-country-code=\"IO\" >Territoire britannique de l\u2019oc\u00e9an Indien<\/option><option value=\"Tha\u00eflande\" data-country-code=\"TH\" >Tha\u00eflande<\/option><option value=\"Timor-Leste\" data-country-code=\"TL\" >Timor-Leste<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad &amp; Tobago\" data-country-code=\"TT\" >Trinidad &amp; Tobago<\/option><option value=\"Tunisie\" data-country-code=\"TN\" >Tunisie<\/option><option value=\"Turkm\u00e9nistan\" data-country-code=\"TM\" >Turkm\u00e9nistan<\/option><option value=\"Turks &amp; Caicos Islands\" data-country-code=\"TC\" >Turks &amp; Caicos Islands<\/option><option value=\"Turquie\" data-country-code=\"TR\" >Turquie<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"U.S. Virgin Islands\" data-country-code=\"VI\" >U.S. Virgin Islands<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >Vietnam<\/option><option value=\"V\u00e9n\u00e9zu\u00e9la\" data-country-code=\"VE\" >V\u00e9n\u00e9zu\u00e9la<\/option><option value=\"Yemen\" data-country-code=\"YE\" >Yemen<\/option><option value=\"Zambie\" data-country-code=\"ZM\" >Zambie<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><option value=\"\u00c9gypte\" data-country-code=\"EG\" >\u00c9gypte<\/option><option value=\"\u00c9mirats arabes unis\" data-country-code=\"AE\" >\u00c9mirats arabes unis<\/option><option value=\"\u00c9quateur\" data-country-code=\"EC\" >\u00c9quateur<\/option><option value=\"\u00c9rythr\u00e9e\" data-country-code=\"ER\" >\u00c9rythr\u00e9e<\/option><option value=\"\u00c9tats-Unis d\u2019Am\u00e9rique (USA)\" data-country-code=\"US\" >\u00c9tats-Unis d\u2019Am\u00e9rique (USA)<\/option><option value=\"\u00c9thiopie\" data-country-code=\"ET\" >\u00c9thiopie<\/option><option value=\"\u00cele Bouvet\" data-country-code=\"BV\" >\u00cele Bouvet<\/option><option value=\"\u00cele Christmas\" data-country-code=\"CX\" >\u00cele Christmas<\/option><option value=\"\u00cele Heard et \u00eele Mcdonald\" data-country-code=\"HM\" >\u00cele Heard et \u00eele Mcdonald<\/option><option value=\"\u00cele Maurice\" data-country-code=\"MU\" >\u00cele Maurice<\/option><option value=\"\u00cele Norfolk\" data-country-code=\"NF\" >\u00cele Norfolk<\/option><option value=\"\u00celes Ca\u00efmans\" data-country-code=\"KY\" >\u00celes Ca\u00efmans<\/option><option value=\"\u00celes Cocos\" data-country-code=\"CC\" >\u00celes Cocos<\/option><option value=\"\u00celes Cook\" data-country-code=\"CK\" >\u00celes Cook<\/option><option value=\"\u00celes Falkland\" data-country-code=\"FK\" >\u00celes Falkland<\/option><option value=\"\u00celes F\u00e9ro\u00e9\" data-country-code=\"FO\" >\u00celes F\u00e9ro\u00e9<\/option><option value=\"\u00celes Mariannes du Nord\" data-country-code=\"MP\" >\u00celes Mariannes du Nord<\/option><option value=\"\u00celes Marshall\" data-country-code=\"MH\" >\u00celes Marshall<\/option><option value=\"\u00celes Pitcairn\" data-country-code=\"PN\" >\u00celes Pitcairn<\/option><option value=\"\u00celes Salomon\" data-country-code=\"SB\" >\u00celes Salomon<\/option><option value=\"\u00celes Wallis et Futuna\" data-country-code=\"WF\" >\u00celes Wallis et Futuna<\/option><option value=\"\u00celes mineures \u00e9loign\u00e9es des \u00c9tats-Unis\" data-country-code=\"UM\" >\u00celes mineures \u00e9loign\u00e9es des \u00c9tats-Unis<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-2\" class=\"forminator-field-phone forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-phone-2_6a97a213432e7\" id=\"forminator-field-phone-2_6a97a213432e7-label\" class=\"forminator-label\">T\u00e9l\u00e9phone <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"phone-2\" value=\"\" placeholder=\"\" id=\"forminator-field-phone-2_6a97a213432e7\" class=\"forminator-input forminator-field--phone\" data-required=\"1\" aria-required=\"true\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-2\" class=\"forminator-field-textarea forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-2_6a97a213432e7\" id=\"forminator-field-textarea-2_6a97a213432e7-label\" class=\"forminator-label\">Texte<\/label><textarea name=\"textarea-2\" placeholder=\"\" id=\"forminator-field-textarea-2_6a97a213432e7\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" ><\/textarea><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"upload-2\" class=\"forminator-field-upload forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-upload-2_6a97a213432e7\" id=\"forminator-field-upload-2_6a97a213432e7-label\" class=\"forminator-label\">T\u00e9l\u00e9verser un fichier<\/label><div class=\"forminator-file-upload \" data-element=\"upload-2_6a97a213432e7\"><input type=\"file\" name=\"upload-2\" id=\"forminator-field-upload-2_6a97a213432e7\" class=\"forminator-input-file\" accept=\".jpg,.jpeg,.jpe,.gif,.png,.bmp,.tiff,.tif,.webp,.avif,.ico,.heic,.heif,.heics,.heifs,.asf,.asx,.wmv,.wmx,.wm,.avi,.divx,.flv,.mov,.qt,.mpeg,.mpg,.mpe,.mp4,.m4v,.ogv,.webm,.mkv,.3gp,.3gpp,.3g2,.3gp2,.txt,.asc,.c,.cc,.h,.srt,.csv,.tsv,.ics,.rtx,.vtt,.mp3,.m4a,.m4b,.aac,.ra,.ram,.wav,.x-wav,.ogg,.oga,.flac,.mid,.midi,.wma,.wax,.mka,.rtf,.pdf,.class,.tar,.zip,.gz,.gzip,.7z,.psd,.xcf,.doc,.pot,.pps,.ppt,.wri,.xla,.xls,.xlt,.xlw,.mdb,.mpp,.docx,.docm,.dotx,.dotm,.xlsx,.xlsm,.xlsb,.xltx,.xltm,.xlam,.pptx,.pptm,.ppsx,.ppsm,.potx,.potm,.ppam,.sldx,.sldm,.onetoc,.onetoc2,.onetmp,.onepkg,.oxps,.xps,.odt,.odp,.ods,.odg,.odc,.odb,.odf,.wp,.wpd,.key,.numbers,.pages,image\/jpeg,image\/gif,image\/png,image\/bmp,image\/tiff,image\/webp,image\/avif,image\/x-icon,image\/heic,image\/heif,image\/heic-sequence,image\/heif-sequence,video\/x-ms-asf,video\/x-ms-wmv,video\/x-ms-wmx,video\/x-ms-wm,video\/avi,video\/divx,video\/x-flv,video\/quicktime,video\/mpeg,video\/mp4,video\/ogg,video\/webm,video\/x-matroska,video\/3gpp,video\/3gpp2,text\/plain,text\/csv,text\/tab-separated-values,text\/calendar,text\/richtext,text\/vtt,audio\/mpeg,audio\/aac,audio\/x-realaudio,audio\/wav,audio\/ogg,audio\/flac,audio\/midi,audio\/x-ms-wma,audio\/x-ms-wax,audio\/x-matroska,application\/rtf,application\/pdf,application\/java,application\/x-tar,application\/zip,application\/x-gzip,application\/x-7z-compressed,application\/octet-stream,application\/msword,application\/vnd.ms-powerpoint,application\/vnd.ms-write,application\/vnd.ms-excel,application\/vnd.ms-access,application\/vnd.ms-project,application\/vnd.openxmlformats-officedocument.wordprocessingml.document,application\/vnd.ms-word.document.macroEnabled.12,application\/vnd.openxmlformats-officedocument.wordprocessingml.template,application\/vnd.ms-word.template.macroEnabled.12,application\/vnd.openxmlformats-officedocument.spreadsheetml.sheet,application\/vnd.ms-excel.sheet.macroEnabled.12,application\/vnd.ms-excel.sheet.binary.macroEnabled.12,application\/vnd.openxmlformats-officedocument.spreadsheetml.template,application\/vnd.ms-excel.template.macroEnabled.12,application\/vnd.ms-excel.addin.macroEnabled.12,application\/vnd.openxmlformats-officedocument.presentationml.presentation,application\/vnd.ms-powerpoint.presentation.macroEnabled.12,application\/vnd.openxmlformats-officedocument.presentationml.slideshow,application\/vnd.ms-powerpoint.slideshow.macroEnabled.12,application\/vnd.openxmlformats-officedocument.presentationml.template,application\/vnd.ms-powerpoint.template.macroEnabled.12,application\/vnd.ms-powerpoint.addin.macroEnabled.12,application\/vnd.openxmlformats-officedocument.presentationml.slide,application\/vnd.ms-powerpoint.slide.macroEnabled.12,application\/onenote,application\/oxps,application\/vnd.ms-xpsdocument,application\/vnd.oasis.opendocument.text,application\/vnd.oasis.opendocument.presentation,application\/vnd.oasis.opendocument.spreadsheet,application\/vnd.oasis.opendocument.graphics,application\/vnd.oasis.opendocument.chart,application\/vnd.oasis.opendocument.database,application\/vnd.oasis.opendocument.formula,application\/wordperfect,application\/vnd.apple.keynote,application\/vnd.apple.numbers,application\/vnd.apple.pages\" tabindex=\"-1\"><button id=\"forminator-field-upload-2_6a97a213432e7_button\" class=\"forminator-button forminator-button-upload\" data-id=\"forminator-field-upload-2_6a97a213432e7\">Choisissez un fichier<\/button><span data-empty-text=\"Aucun fichier s\u00e9lectionn\u00e9\">Aucun fichier s\u00e9lectionn\u00e9<\/span><button class=\"forminator-button-delete\" style=\"display: none;\"><i class=\"forminator-icon-close\" aria-hidden=\"true\"><\/i><span class=\"forminator-screen-reader-only\">Supprimer le fichier t\u00e9l\u00e9vers\u00e9<\/span><\/button><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"radio-1\" class=\"forminator-field-radio forminator-col forminator-col-12 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-radio-1-6a97a213432e7-label\"><span id=\"forminator-radiogroup-radio-1-6a97a213432e7-label\" class=\"forminator-label\">Choisir un mode de livraison <span class=\"forminator-required\">*<\/span><\/span><label id=\"forminator-field-radio-1-label-1\" for=\"forminator-field-radio-1-1-6a97a213432e7\" class=\"forminator-radio\" title=\"Livraison en relai 2-5\u20ac\"><input type=\"radio\" name=\"radio-1\" value=\"one\" id=\"forminator-field-radio-1-1-6a97a213432e7\" aria-labelledby=\"forminator-field-radio-1-label-1\" data-calculation=\"5\"   data-hidden-behavior=\"zero\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Livraison en relai 2-5\u20ac<\/span><\/label><label id=\"forminator-field-radio-1-label-2\" for=\"forminator-field-radio-1-2-6a97a213432e7\" class=\"forminator-radio\" title=\"Livraison \u00e0 l&#039;adresse 6-15\u20ac\"><input type=\"radio\" name=\"radio-1\" value=\"two\" id=\"forminator-field-radio-1-2-6a97a213432e7\" aria-labelledby=\"forminator-field-radio-1-label-2\" data-calculation=\"10\"   data-hidden-behavior=\"zero\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Livraison \u00e0 l'adresse 6-15\u20ac<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"html-1\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-1\"><label class=\"forminator-label\">HTML<\/label><\/div><\/div><\/div><div class=\"forminator-row forminator-action-buttons\"><div class=\"forminator-col forminator-col-12\"><input type=\"button\" value=\"Ajout d&#039;adresse\" class=\"forminator-repeater-action-button forminator-repeater-add\" \/><input type=\"button\" value=\"Retirer l&#039;adresse\" class=\"forminator-repeater-action-button forminator-repeater-remove\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div\n\t\t\t\ttabindex=\"-1\"\n\t\t\t\trole=\"tabpanel\"\n\t\t\t\tid=\"forminator-custom-form-595--page-1\"\n\t\t\t\tclass=\"forminator-pagination\"\n\t\t\t\taria-labelledby=\"forminator-custom-form-595--page-1-label\"\n\t\t\t\taria-hidden=\"true\"\n\t\t\t\tdata-step=\"1\"\n\t\t\t\tdata-label=\"Page 1\"\n\t\t\t\tdata-actual-label=\"Page 2\"\n\t\t\t\tdata-name=\"\"\n\t\t\t\thidden\n\t\t\t><div class=\"forminator-pagination--content\"><\/div><button class=\"forminator-button forminator-pagination-submit\" style=\"display: none;\" disabled>Envoyer<\/button><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"6c80a71d47\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/10\" \/><input type=\"hidden\" name=\"form_id\" value=\"595\"><input type=\"hidden\" name=\"page_id\" value=\"10\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/antsound.net\/index.php\/demander-une-expedition\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":41,"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":599,"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions\/599"}],"wp:attachment":[{"href":"https:\/\/antsound.net\/index.php\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}